{"id":543,"date":"2008-11-28T00:00:00","date_gmt":"2008-11-27T22:00:00","guid":{"rendered":"http:\/\/antonioteiza.org\/publicacin-del-libro-azkoitia-y-los-oteiza\/"},"modified":"2008-11-28T00:00:00","modified_gmt":"2008-11-27T22:00:00","slug":"publicacin-del-libro-azkoitia-y-los-oteiza","status":"publish","type":"post","link":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/","title":{"rendered":"Publicaci&oacute;n del libro Azkoitia y los Oteiza"},"content":{"rendered":"<p>El libro Azkoitia y los Oteiza est&aacute; basado en la estrecha relaci&oacute;n de los hermanos Oteiza y Azkoitia; adem&aacute;s de ser tierra de sus antepasados, ambos artistas han dejado un importante legado art&iacute;stico en Azkoitia. El libro ha sido publicado por el Ayuntamiento de Azkoitia y la Fundaci&oacute;n Antonio Oteiza y ha contado con el apoyo de Kutxa.<\/p>\n<p>El libro ha sido editado en castellano y euskara y cuenta con alrededor de 60 p&aacute;ginas. En ellas podremos descubrir la historia de los antepasados de los hermanos Oteiza, viajando por el caser&iacute;o Olabazeta e Izarraitz. Tambi&eacute;n conoceremos m&aacute;s de cerca el legado art&iacute;stico que ambos artistas han dejado en nuestras calles: la escultura de Batarrabi, los Frontones Jorge Oteiza, la escultura en homenaje a Nicol&aacute;s de Armentia&#8230;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est&aacute; basado en la estrecha relaci&oacute;n de los hermanos Oteiza y Azkoitia<\/p>\n","protected":false},"author":1,"featured_media":541,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ekimenak"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Publicaci&oacute;n del libro Azkoitia y los Oteiza - Antonio Oteiza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Publicaci&oacute;n del libro Azkoitia y los Oteiza - Antonio Oteiza\" \/>\n<meta property=\"og:description\" content=\"Est&aacute; basado en la estrecha relaci&oacute;n de los hermanos Oteiza y Azkoitia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/\" \/>\n<meta property=\"og:site_name\" content=\"Antonio Oteiza\" \/>\n<meta property=\"article:published_time\" content=\"2008-11-27T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/antonioteiza.org\/wp-content\/uploads\/2022\/08\/libro_azkoitia_y_los_oteiza-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"100\" \/>\n\t<meta property=\"og:image:height\" content=\"106\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kudeatzailea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"kudeatzailea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/\"},\"author\":{\"name\":\"kudeatzailea\",\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/#\\\/schema\\\/person\\\/2b87cebc07495c820ce05edf65e95a0d\"},\"headline\":\"Publicaci&oacute;n del libro Azkoitia y los Oteiza\",\"datePublished\":\"2008-11-27T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/\"},\"wordCount\":156,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/antonioteiza.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/libro_azkoitia_y_los_oteiza-1.jpg\",\"articleSection\":[\"Ekimenak\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/\",\"url\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/\",\"name\":\"Publicaci&oacute;n del libro Azkoitia y los Oteiza - Antonio Oteiza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/antonioteiza.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/libro_azkoitia_y_los_oteiza-1.jpg\",\"datePublished\":\"2008-11-27T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/antonioteiza.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/libro_azkoitia_y_los_oteiza-1.jpg\",\"contentUrl\":\"https:\\\/\\\/antonioteiza.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/libro_azkoitia_y_los_oteiza-1.jpg\",\"width\":100,\"height\":106},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/publicacin-del-libro-azkoitia-y-los-oteiza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publicaci&oacute;n del libro Azkoitia y los Oteiza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/\",\"name\":\"Antonio Oteiza\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/#organization\",\"name\":\"Antonio Oteiza\",\"url\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/antonioteiza.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-oteiza-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/antonioteiza.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-oteiza-logo.jpg\",\"width\":256,\"height\":91,\"caption\":\"Antonio Oteiza\"},\"image\":{\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/antonioteiza.org\\\/es\\\/#\\\/schema\\\/person\\\/2b87cebc07495c820ce05edf65e95a0d\",\"name\":\"kudeatzailea\",\"sameAs\":[\"https:\\\/\\\/antonioteiza.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Publicaci&oacute;n del libro Azkoitia y los Oteiza - Antonio Oteiza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/","og_locale":"es_ES","og_type":"article","og_title":"Publicaci&oacute;n del libro Azkoitia y los Oteiza - Antonio Oteiza","og_description":"Est&aacute; basado en la estrecha relaci&oacute;n de los hermanos Oteiza y Azkoitia","og_url":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/","og_site_name":"Antonio Oteiza","article_published_time":"2008-11-27T22:00:00+00:00","og_image":[{"width":100,"height":106,"url":"https:\/\/antonioteiza.org\/wp-content\/uploads\/2022\/08\/libro_azkoitia_y_los_oteiza-1.jpg","type":"image\/jpeg"}],"author":"kudeatzailea","twitter_card":"summary_large_image","twitter_misc":{"Written by":"kudeatzailea","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/#article","isPartOf":{"@id":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/"},"author":{"name":"kudeatzailea","@id":"https:\/\/antonioteiza.org\/es\/#\/schema\/person\/2b87cebc07495c820ce05edf65e95a0d"},"headline":"Publicaci&oacute;n del libro Azkoitia y los Oteiza","datePublished":"2008-11-27T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/"},"wordCount":156,"commentCount":0,"publisher":{"@id":"https:\/\/antonioteiza.org\/es\/#organization"},"image":{"@id":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/#primaryimage"},"thumbnailUrl":"https:\/\/antonioteiza.org\/wp-content\/uploads\/2022\/08\/libro_azkoitia_y_los_oteiza-1.jpg","articleSection":["Ekimenak"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/","url":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/","name":"Publicaci&oacute;n del libro Azkoitia y los Oteiza - Antonio Oteiza","isPartOf":{"@id":"https:\/\/antonioteiza.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/#primaryimage"},"image":{"@id":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/#primaryimage"},"thumbnailUrl":"https:\/\/antonioteiza.org\/wp-content\/uploads\/2022\/08\/libro_azkoitia_y_los_oteiza-1.jpg","datePublished":"2008-11-27T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/#primaryimage","url":"https:\/\/antonioteiza.org\/wp-content\/uploads\/2022\/08\/libro_azkoitia_y_los_oteiza-1.jpg","contentUrl":"https:\/\/antonioteiza.org\/wp-content\/uploads\/2022\/08\/libro_azkoitia_y_los_oteiza-1.jpg","width":100,"height":106},{"@type":"BreadcrumbList","@id":"https:\/\/antonioteiza.org\/es\/publicacin-del-libro-azkoitia-y-los-oteiza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/antonioteiza.org\/es\/"},{"@type":"ListItem","position":2,"name":"Publicaci&oacute;n del libro Azkoitia y los Oteiza"}]},{"@type":"WebSite","@id":"https:\/\/antonioteiza.org\/es\/#website","url":"https:\/\/antonioteiza.org\/es\/","name":"Antonio Oteiza","description":"Just another WordPress site","publisher":{"@id":"https:\/\/antonioteiza.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/antonioteiza.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/antonioteiza.org\/es\/#organization","name":"Antonio Oteiza","url":"https:\/\/antonioteiza.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/antonioteiza.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/antonioteiza.org\/wp-content\/uploads\/2022\/06\/cropped-oteiza-logo.jpg","contentUrl":"https:\/\/antonioteiza.org\/wp-content\/uploads\/2022\/06\/cropped-oteiza-logo.jpg","width":256,"height":91,"caption":"Antonio Oteiza"},"image":{"@id":"https:\/\/antonioteiza.org\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/antonioteiza.org\/es\/#\/schema\/person\/2b87cebc07495c820ce05edf65e95a0d","name":"kudeatzailea","sameAs":["https:\/\/antonioteiza.org"]}]}},"_links":{"self":[{"href":"https:\/\/antonioteiza.org\/es\/wp-json\/wp\/v2\/posts\/543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antonioteiza.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/antonioteiza.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/antonioteiza.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antonioteiza.org\/es\/wp-json\/wp\/v2\/comments?post=543"}],"version-history":[{"count":0,"href":"https:\/\/antonioteiza.org\/es\/wp-json\/wp\/v2\/posts\/543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antonioteiza.org\/es\/wp-json\/wp\/v2\/media\/541"}],"wp:attachment":[{"href":"https:\/\/antonioteiza.org\/es\/wp-json\/wp\/v2\/media?parent=543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antonioteiza.org\/es\/wp-json\/wp\/v2\/categories?post=543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antonioteiza.org\/es\/wp-json\/wp\/v2\/tags?post=543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}